{"id":568,"date":"2024-08-09T15:58:08","date_gmt":"2024-08-09T13:58:08","guid":{"rendered":"https:\/\/brauexterior.com\/?page_id=568"},"modified":"2024-09-04T15:58:58","modified_gmt":"2024-09-04T13:58:58","slug":"showroom-2-4","status":"publish","type":"page","link":"https:\/\/brauexterior.com\/index.php\/en\/showroom-2-4\/","title":{"rendered":"Showroom 2-EN"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px||false|false\u00bb custom_padding_tablet=\u00bb||0px||false|false\u00bb custom_padding_phone=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbd72c0383-6487-4f2c-ac5c-7d48a6376757&#8243; header_font=\u00bbKrona One|||on|||||\u00bb header_text_color=\u00bb#E1D9D7&#8243; header_font_size=\u00bb70px\u00bb header_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb header_font_size_tablet=\u00bb50px\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Sal\u00f3n BiColor<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bb381dae94-24d7-4aff-b920-d622376eafad\u00bb header_5_font=\u00bbSacramento||||||||\u00bb header_5_text_color=\u00bb#000000&#8243; header_5_font_size=\u00bb80px\u00bb header_5_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb-70px||||false|false\u00bb custom_margin_tablet=\u00bb-80px||||false|false\u00bb custom_margin_phone=\u00bb-60px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb header_5_font_size_tablet=\u00bb40px\u00bb header_5_font_size_phone=\u00bb34px\u00bb header_5_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h5>Brau Living Outside<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-10px||||false|false\u00bb custom_margin_tablet=\u00bb-10px||||false|false\u00bb custom_margin_phone=\u00bb-25px||0px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb|0px|0px|0px|false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb98%\u00bb width_last_edited=\u00bbon|phone\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/brauexterior.com\/wp-content\/uploads\/2024\/08\/Showroom-2-EN-Numbered.jpg\u00bb alt=\u00bbal\u00f3n BRAU de &#8216;Exterior bicolor&#8217; &#8211; Muebles de jard\u00edn estilo Marrakech.\u00bb title_text=\u00bbShowroom 2 &#8211; EN &#8211; Numbered\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|phone\u00bb max_width=\u00bb100%\u00bb height_tablet=\u00bb\u00bb height_phone=\u00bb\u00bb height_last_edited=\u00bbon|phone\u00bb border_width_all=\u00bb2px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_blur=\u00bb8px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbformentera\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb628&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_text=\u00bb1&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb628&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb628&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb628&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb389&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/en\/product\/lanzarote\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbformentera\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb617&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_2&#8243;][et_pb_button button_text=\u00bb2&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb617&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb617&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb617&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb389&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/product\/sillon-mallorca\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbpalma\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||||false|false\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb396&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_2&#8243;][et_pb_button button_text=\u00bb3&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb396&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb540&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb540&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb351&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/en\/product\/palma\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbformentera\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb510&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_2&#8243;][et_pb_button button_text=\u00bb4&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb510&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb510&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb510&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb389&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/en\/product\/natural-palm-leaf-umbrella\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbtenerife\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb507&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_2&#8243;][et_pb_button button_text=\u00bb5&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb507&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb507&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb507&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb396&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/en\/product\/black-cactus-silk-cushion\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_id=\u00bbmenorca\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_wc_images product=\u00bb498&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_2&#8243;][et_pb_button button_text=\u00bb6&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb1px\u00bb button_border_radius=\u00bb50px\u00bb button_font=\u00bbKrona One||||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_title product=\u00bb498&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbKrona One||||||||\u00bb global_colors_info=\u00bb{}\u00bb header_text_align=\u00bbleft\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb10px|50%||-85%|false|false\u00bb custom_margin_phone=\u00bb0px|0%|-10px|0%|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_margin_tablet=\u00bb10px|50%||-85%|false|false\u00bb][\/et_pb_wc_title][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_description product=\u00bb498&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbABeeZee|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_description][et_pb_wc_price product=\u00bb498&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbKrona One||||||||\u00bb body_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_wc_add_to_cart product=\u00bb417&#8243; show_quantity=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One|||on|||||\u00bb button_custom_margin=\u00bb0px||0px||false|false\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb4px\u00bb box_shadow_vertical_button=\u00bb4px\u00bb box_shadow_blur_button=\u00bb6px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/brauexterior.com\/index.php\/en\/product\/outdoor-wicker-rug\/\u00bb button_text=\u00bbMore Details\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb12px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#f7f2ef\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbKrona One|700||on|||||\u00bb custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb custom_padding_phone=\u00bb14px|20px|14px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb6px\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bb#ffffff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb module_id=\u00bbcontact\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb0deg\u00bb background_color_gradient_stops=\u00bb#f7f2ef 1%|#f7f2ef 76%|rgba(255,255,255,0) 76%\u00bb custom_margin=\u00bb|0px||0px|false|true\u00bb custom_margin_tablet=\u00bb|0px||0px|false|true\u00bb custom_margin_phone=\u00bb|0px||0px|false|true\u00bb background_last_edited=\u00bboff|desktop\u00bb background_enable_color_tablet=\u00bboff\u00bb use_background_color_gradient_tablet=\u00bbon\u00bb background_color_gradient_stops_tablet=\u00bb#e1d9d7 80%|rgba(255,255,255,0) 80%\u00bb global_module=\u00bb502&#8243; saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb65%\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/brauexterior.com\/wp-content\/uploads\/2024\/06\/Hogar-dulce-Jardin-1.jpg\u00bb alt=\u00bbSilla de exterior estilo tradicional de Marrakech\u00bb title_text=\u00bbHogar dulce Jard\u00edn (1)\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bboff|1000px|1000px||\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb4px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/brauexterior.com\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-05-31-at-19.57.04.jpeg\u00bb title_text=\u00bbWhatsApp Image 2024-05-31 at 19.57.04&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb transform_translate=\u00bb0px|-50px\u00bb transform_translate_linked=\u00bboff\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbcenter_left\u00bb horizontal_offset=\u00bb-30px\u00bb width=\u00bb50%\u00bb max_width_tablet=\u00bb200px\u00bb max_width_phone=\u00bb150px\u00bb max_width_last_edited=\u00bboff|desktop\u00bb custom_margin=\u00bb|||-3vw|false|false\u00bb custom_margin_tablet=\u00bb0%|||0%|false|false\u00bb custom_margin_phone=\u00bb0%|||0%|false|false\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb border_width_all=\u00bb2px\u00bb border_color_all=\u00bb#0C71C3&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_blur=\u00bb3px\u00bb box_shadow_spread=\u00bb-3px\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb60px||60px||true|false\u00bb custom_padding_tablet=\u00bb20px||20px||true|false\u00bb custom_padding_phone=\u00bb0px||0px||true|false\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb7b39e609-07da-4c2d-b385-8265485d0349&#8243; text_font_size=\u00bb13px\u00bb header_2_font=\u00bbKrona One|||on|||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb36px\u00bb header_2_line_height=\u00bb1.2em\u00bb text_font_tablet=\u00bb\u00bb text_font_phone=\u00bb\u00bb text_font_last_edited=\u00bbon|desktop\u00bb header_2_font_size_tablet=\u00bb50px\u00bb header_2_font_size_phone=\u00bb27px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Contact Us<\/h2>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bb3a5fa9a7-7987-4564-89a5-37b87a5b6ad8&#8243; header_3_font=\u00bbKrona One||||||||\u00bb header_3_font_size=\u00bb32px\u00bb header_3_line_height=\u00bb1.4em\u00bb header_3_font_size_tablet=\u00bb20px\u00bb header_3_font_size_phone=\u00bb16px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><a href=\"#\">(255) 352-6258<\/a><\/h3>\n<p>[\/et_pb_text][et_pb_contact_form email=\u00bbbraulivingspain@gmail.com\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb _unique_id=\u00bbed842779-2a80-4034-b72c-daa42cc9a733&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_font=\u00bbKrona One||||||||\u00bb button_icon=\u00bb&#x4e;||divi||400&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbName\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbEmail\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMessage\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_4,1_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb60px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bb3a5fa9a7-7987-4564-89a5-37b87a5b6ad8&#8243; header_3_font=\u00bbKrona One||||||||\u00bb header_3_font_size=\u00bb32px\u00bb header_3_line_height=\u00bb1.4em\u00bb header_3_font_size_tablet=\u00bb20px\u00bb header_3_font_size_phone=\u00bb16px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Newsletter<\/h3>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00bbelegantthemestest|1ea2bbd026&#8243; first_name_field=\u00bboff\u00bb last_name_field=\u00bboff\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb form_field_background_color=\u00bbRGBA(255,255,255,0)\u00bb form_field_text_color=\u00bb#000000&#8243; form_field_custom_padding=\u00bb|0px||0px|false|true\u00bb form_field_font=\u00bbMontserrat|500|||||||\u00bb use_background_color=\u00bboff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#0C71C3&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb4px\u00bb button_font=\u00bbKrona One|||on|||||\u00bb button_custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb button_custom_padding_tablet=\u00bb16px|28px|16px|28px|true|true\u00bb button_custom_padding_phone=\u00bb14px|24px|14px|24px|true|true\u00bb button_custom_padding_last_edited=\u00bboff|desktop\u00bb background_layout=\u00bblight\u00bb button_text_size_tablet=\u00bb15px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bboff|desktop\u00bb border_radii_fields=\u00bbon|0px|0px|0px|0px\u00bb border_color_all_fields=\u00bb#000000&#8243; border_width_bottom_fields=\u00bb2px\u00bb global_colors_info=\u00bb{}\u00bb button_text_color__hover_enabled=\u00bboff|hover\u00bb button_bg_color__hover_enabled=\u00bboff|desktop\u00bb button_bg_color__hover=\u00bb#372E2B\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_signup][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"#\">Home<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<a href=\"#\">About Us<\/a>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"#\">Resources<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"#\">About<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"#\">Design<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<a href=\"#\">Showroom<\/a>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<a href=\"#\">Resume<\/a>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbaec0be99-8a53-4f75-abf2-64f29a8b4cc2&#8243; text_font=\u00bbKrona One||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb link_text_color=\u00bb#000000&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"#\">Gallery<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sal\u00f3n BiColorBrau Living OutsideContact Us(255) 352-6258NewsletterHomeAbout UsResourcesAboutDesignShowroomResumeGallery<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-568","page","type-page","status-publish","hentry"],"aioseo_notices":[],"lang":"en","translations":{"en":568,"es":348},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/pages\/568"}],"collection":[{"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/comments?post=568"}],"version-history":[{"count":30,"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/pages\/568\/revisions"}],"predecessor-version":[{"id":938,"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/pages\/568\/revisions\/938"}],"wp:attachment":[{"href":"https:\/\/brauexterior.com\/index.php\/wp-json\/wp\/v2\/media?parent=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}